{"id":6835,"date":"2025-01-04T22:14:02","date_gmt":"2025-01-05T03:14:02","guid":{"rendered":"https:\/\/www.lintyco.com\/?p=6835"},"modified":"2025-02-02T02:34:30","modified_gmt":"2025-02-02T07:34:30","slug":"the-ultimate-faq-guide-liquid-filling-machinery","status":"publish","type":"post","link":"https:\/\/www.lintyco.com\/es\/the-ultimate-faq-guide-liquid-filling-machinery\/","title":{"rendered":"Maximizaci\u00f3n de la eficiencia con maquinaria de envasado de l\u00edquidos: su gu\u00eda de preguntas frecuentes todo en uno"},"content":{"rendered":"<p>Con el paso del tiempo, las m\u00e1quinas envasadoras de l\u00edquidos se han convertido en una parte insustituible de diversas industrias, como alimentos y bebidas, productos farmac\u00e9uticos y de cuidado personal. Las m\u00e1quinas de envasado de l\u00edquidos se dividen principalmente en dos tipos, envases de l\u00edquidos flexibles y envases de l\u00edquidos r\u00edgidos. El primero se envasa principalmente en bolsas, mientras que el segundo se envasa principalmente en botellas y tarros. En el siguiente art\u00edculo, puede obtener informaci\u00f3n sobre las categor\u00edas de m\u00e1quinas de envasado de l\u00edquidos, los m\u00e9todos de mantenimiento y c\u00f3mo ayudarlo a elegir la m\u00e1quina de envasado pr\u00e1ctica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de maquinaria de envasado de l\u00edquidos<\/h2>\n\n\n\n<p>Los tipos m\u00e1s comunes de soluciones de envasado de l\u00edquidos son la m\u00e1quina llenadora de botellas, la m\u00e1quina llenadora de bolsas y la m\u00e1quina llenadora de tubos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las m\u00e1quinas llenadoras de botellas se utilizan para llenar l\u00edquidos en botellas de vidrio o pl\u00e1stico a altas velocidades. Se encuentran com\u00fanmente en la industria de bebidas llenando jugos, aguas, refrescos y m\u00e1s.<\/li>\n\n\n\n<li>Las m\u00e1quinas llenadoras de bolsas est\u00e1n dise\u00f1adas para llenar l\u00edquidos en bolsas o bolsas flexibles. Son ampliamente utilizados para productos alimenticios como sopas, salsas y alimentos para beb\u00e9s.<\/li>\n\n\n\n<li>Las m\u00e1quinas llenadoras de tubos son m\u00e1quinas especializadas que llenan con precisi\u00f3n l\u00edquidos en tubos, generalmente para productos de cuidado personal como pasta de dientes, lociones y champ\u00fas.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"6838\" src=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-683x1024.jpg\" alt=\"m\u00e1quina de llenado de l\u00edquido de bolsa\" class=\"wp-image-6838\" srcset=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-683x1024.jpg 683w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-200x300.jpg 200w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-768x1152.jpg 768w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-1024x1536.jpg 1024w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-1365x2048.jpg 1365w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-8x12.jpg 8w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-600x900.jpg 600w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/3988de1a-71a1-4230-9182-0c58f4544aab-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina de llenado de l\u00edquido de bolsa<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img alt=\"\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"6837\" src=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-683x1024.jpg\" class=\"wp-image-6837\" srcset=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-683x1024.jpg 683w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-200x300.jpg 200w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-768x1152.jpg 768w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-1024x1536.jpg 1024w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-1365x2048.jpg 1365w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-8x12.jpg 8w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-600x900.jpg 600w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/07a3c09a-b3c5-4894-8eba-705d8618b812-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina de llenado de tubos<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"6836\" src=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-683x1024.jpg\" alt=\"m\u00e1quina de llenado de botellas\" class=\"wp-image-6836\" srcset=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-683x1024.jpg 683w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-200x300.jpg 200w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-768x1152.jpg 768w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-1024x1536.jpg 1024w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-1365x2048.jpg 1365w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-8x12.jpg 8w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-600x900.jpg 600w, https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/07\/a3fd085c-95e2-4716-a9ae-08b77e35ec4e-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina de llenado de l\u00edquidos de botellas<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Caracter\u00edsticas clave que debe buscar en la maquinaria de envasado de l\u00edquidos<\/h2>\n\n\n\n<p>Al evaluar las m\u00e1quinas de envasado de l\u00edquidos, busque:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Altas velocidades de llenado: medidas en botellas\/bolsas por minuto. Las velocidades m\u00e1s r\u00e1pidas significan una mayor productividad.<\/li>\n\n\n\n<li>Precisi\u00f3n: control de volumen de llenado de precisi\u00f3n para minimizar el desperdicio de producto.<\/li>\n\n\n\n<li>Flexibilidad: Capacidad para manejar diferentes tipos de envases y vol\u00famenes de llenado.<\/li>\n\n\n\n<li>Facilidad de uso: operaci\u00f3n e interfaz simples para minimizar los requisitos de capacitaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">El papel de la automatizaci\u00f3n en el envasado de l\u00edquidos<\/h2>\n\n\n\n<p>Las m\u00e1quinas autom\u00e1ticas de envasado de l\u00edquidos ofrecen muchos beneficios, como precisi\u00f3n constante, mayor rendimiento y costos de mano de obra reducidos. Las tecnolog\u00edas emergentes en torno a la visi\u00f3n artificial, los sensores inteligentes y la rob\u00f3tica est\u00e1n impulsando una mayor automatizaci\u00f3n en el envasado de l\u00edquidos. Puedes referirte a <a href=\"https:\/\/www.marketsandmarkets.com\/Market-Reports\/liquid-packaging-market-120112267.html\">el pron\u00f3stico mundial para las m\u00e1quinas de envasado de l\u00edquidos<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona la m\u00e1quina envasadora de bolsas para l\u00edquidos?<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Paso<\/th><th>Descripci\u00f3n<\/th><\/tr><\/thead><tbody><tr><td>1<\/td><td>Transfiera el material l\u00edquido al dispositivo de medici\u00f3n a trav\u00e9s del tubo de alimentaci\u00f3n.<\/td><\/tr><tr><td>2<\/td><td>Coloque el material de embalaje en la m\u00e1quina para hacer bolsas y s\u00e9llelo en una bolsa vac\u00eda con el dispositivo de sellado t\u00e9rmico<\/td><\/tr><tr><td>3<\/td><td>Tire de la bolsa vac\u00eda hasta el puerto de llenado mediante el dispositivo de tracci\u00f3n e inyecte el material l\u00edquido medido en la bolsa<\/td><\/tr><tr><td>4<\/td><td>Selle la bolsa llena con el dispositivo de sellado t\u00e9rmico e imprima la fecha, el n\u00famero de lote y otra informaci\u00f3n<\/td><\/tr><tr><td>5<\/td><td>Corte la bolsa sellada con el dispositivo de corte y forme la bolsa de embalaje terminada<\/td><\/tr><tr><td>6<\/td><td>Descargue la bolsa de empaque terminada a trav\u00e9s de la salida y rec\u00f3jala o transp\u00f3rtela al siguiente proceso<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"LTC8-200 autom\u00e1tico doypack L\u00edquido Llenado de aceite de palma M\u00e1quina de envasado y sellado\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/44F1J8oL_b0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona la m\u00e1quina de llenado de l\u00edquidos de botellas?<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Paso<\/th><th>Descripci\u00f3n<\/th><\/tr><\/thead><tbody><tr><td>1<\/td><td>Las botellas vac\u00edas son transferidas por el transportador de aire a la m\u00e1quina 3 en 1 de enjuague, llenado y tapado por la rueda de marcaci\u00f3n de botellas<\/td><\/tr><tr><td>2<\/td><td>La abrazadera de la botella en la placa giratoria de la m\u00e1quina de enjuague sujeta la boca de la botella y la voltea 180\u00b0, haciendo que la botella boca abajo<\/td><\/tr><tr><td>3<\/td><td>En un \u00e1rea espec\u00edfica de la m\u00e1quina de enjuague, la boquilla de enjuague roc\u00eda agua de enjuague para enjuagar la pared interna de la botella<\/td><\/tr><tr><td>4<\/td><td>Despu\u00e9s de enjuagar y drenar, la abrazadera de la botella sujeta la boca de la botella a lo largo del riel gu\u00eda y la voltea 180\u00b0, haciendo que la boca de la botella quede hacia arriba.<\/td><\/tr><tr><td>5<\/td><td>Las botellas limpias son exportadas por la rueda de marcaci\u00f3n de botellas desde la m\u00e1quina de enjuague y transferidas a la m\u00e1quina de llenado.<\/td><\/tr><tr><td>6<\/td><td>Las botellas que ingresan a la m\u00e1quina de llenado son sujetadas por la placa del cuello de la botella y levantadas por la leva, y luego la boca de la botella abre la v\u00e1lvula de llenado<\/td><\/tr><tr><td>7<\/td><td>El llenado adopta el m\u00e9todo de llenado por gravedad<\/td><\/tr><tr><td>8<\/td><td>Despu\u00e9s del llenado, la boca de la botella cae y sale de la v\u00e1lvula de llenado, y la rueda de marcaci\u00f3n de transici\u00f3n del cuello de la botella transfiere la botella a la m\u00e1quina tapadora<\/td><\/tr><tr><td>9<\/td><td>La cuchilla antirrotaci\u00f3n de la m\u00e1quina taponadora sujeta el cuello de la botella para mantener la botella en posici\u00f3n vertical y evitar la rotaci\u00f3n.<\/td><\/tr><tr><td>10<\/td><td>El cabezal de tapado de la m\u00e1quina tapadora sigue girando y girando, y realiza acciones como agarrar tapas, cubrir tapas, tapar y soltar tapas bajo la acci\u00f3n de la leva.<\/td><\/tr><tr><td>11<\/td><td>Las botellas terminadas se transfieren de la m\u00e1quina taponadora a la cadena transportadora de salida mediante la rueda selectora de salida de botellas y luego se transportan fuera de la m\u00e1quina 3 en 1.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona la m\u00e1quina de sellado de tubos?<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Paso<\/th><th>Descripci\u00f3n<\/th><\/tr><\/thead><tbody><tr><td>1<\/td><td>Transfiera la manguera a la m\u00e1quina de llenado y sellado por la cinta transportadora<\/td><\/tr><tr><td>2<\/td><td>Use el sensor fotoel\u00e9ctrico para detectar la posici\u00f3n y orientaci\u00f3n de la manguera<\/td><\/tr><tr><td>3<\/td><td>Utilice el manipulador para agarrar la manguera e insertarla en la estaci\u00f3n de llenado y sellado<\/td><\/tr><tr><td>4<\/td><td>Use la bomba de pist\u00f3n o la bomba perist\u00e1ltica para llenar el material l\u00edquido en la manguera de acuerdo con el volumen preestablecido<\/td><\/tr><tr><td>5<\/td><td>Use el dispositivo de calentamiento para sellar la cola de la manguera doblando, engarzando o soldando por ultrasonidos<\/td><\/tr><tr><td>6<\/td><td>Use la impresora de inyecci\u00f3n de tinta o el dispositivo de estampado para imprimir la fecha, el n\u00famero de lote y otra informaci\u00f3n en la cola de la manguera<\/td><\/tr><tr><td>7<\/td><td>Utilice el manipulador para sacar la manguera terminada y transferirla al siguiente proceso o recogerla<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Consejos de mantenimiento y soluci\u00f3n de problemas para maquinaria de envasado de l\u00edquidos<\/h2>\n\n\n\n<p>El mantenimiento adecuado y la resoluci\u00f3n r\u00e1pida de problemas hacen que las m\u00e1quinas de envasado de l\u00edquidos funcionen de manera \u00f3ptima. Tenga procedimientos establecidos para el mantenimiento preventivo e inspeccione las m\u00e1quinas en busca de problemas como obstrucciones, fugas y burbujas en el relleno. Mantenga las piezas de repuesto a mano para reparaciones r\u00e1pidas.<br><strong>puede consultar el archivo de mantenimiento a continuaci\u00f3n<\/strong><br><a href=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/05\/rotary-pouch-packaging-machine-maintence-lintyco.pdf\">Detalle de mantenimiento para m\u00e1quina de envasado, llenado y sellado de bolsas prefabricadas<\/a><br><a href=\"https:\/\/www.lintyco.com\/wp-content\/uploads\/2023\/05\/packaging-equipment-maintence-vffs-packaging-machine.pdf\">\u00bfDetalle de mantenimiento para su empaquetadora VFFS?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo elegir la maquinaria de envasado de l\u00edquidos adecuada para su negocio<\/h2>\n\n\n\n<p>Se deben considerar varios factores al seleccionar la maquinaria de envasado de l\u00edquidos adecuada para sus necesidades:<\/p>\n\n\n\n<p>Capacidad de producci\u00f3n: \u00bfCu\u00e1ntas botellas, bolsas o tubos necesita llenar por minuto? Haga coincidir su producci\u00f3n requerida con la velocidad de llenado de la m\u00e1quina.<\/p>\n\n\n\n<p>Tipo de producto: Los tipos de l\u00edquidos van desde agua hasta jarabe y lociones viscosas. Elija una m\u00e1quina compatible con su producto espec\u00edfico.<\/p>\n\n\n\n<p>Material de embalaje: \u00bfBotellas de vidrio o de pl\u00e1stico? \u00bfBolsas o tubos? Aseg\u00farese de que la m\u00e1quina pueda manejar sus materiales de embalaje.<\/p>\n\n\n\n<p>Presupuesto: considere sus limitaciones presupuestarias para reducir las opciones y satisfacer sus necesidades de manera asequible.<\/p>\n\n\n\n<p>ROI: calcule el potencial de retorno de la inversi\u00f3n de la m\u00e1quina en funci\u00f3n de factores como el aumento de la producci\u00f3n y el ahorro de mano de obra. Apunte a un per\u00edodo de retorno de la inversi\u00f3n de 1 a 3 a\u00f1os. <a href=\"https:\/\/www.lintyco.com\/es\/download\/roi-calculator\/\"><strong>Obtenga GRATIS su Calculadora de ROI para Equipos de Empaque<\/strong><\/a><\/p>\n\n\n\n<p>Proveedor: Trabaje con una empresa de maquinaria de embalaje de confianza que pueda proporcionarle la m\u00e1quina adecuada para su aplicaci\u00f3n y ofrecer asistencia durante la vida \u00fatil del equipo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Seleccionar la maquinaria de envasado de l\u00edquidos adecuada para sus necesidades de producci\u00f3n espec\u00edficas, tipos de productos y restricciones presupuestarias es esencial para una operaci\u00f3n de envasado exitosa. Trabaje en estrecha colaboraci\u00f3n con un proveedor de confianza para evaluar las opciones en funci\u00f3n de sus requisitos y objetivos. si tiene alguna pregunta, no dude en contactarnos <\/p>","protected":false},"excerpt":{"rendered":"<p>With the passing of time, liquid packaging machines have become an irreplaceable part of various industries, such as food and beverages, pharmaceuticals and personal care products. Liquid packaging machines are mainly divided into two types, flexible liquid packaging and rigid liquid packaging. The former is mainly packaged in bags, while the latter is mainly in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Liquid Packaging Machine:Ultimate Guide--LIntyco Pack","_seopress_titles_desc":"Keep up with the ever-evolving liquied packaging industry. This article covers ways to maintain, choose and categorize machines, as well as automation technologies like machine vision and robotics, to help your fill operations run smoother. Get insights on bottle filler, pouch filler, and tube filler machines to best fit your production needs.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[36],"tags":[270],"class_list":["post-6835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liquids","tag-liquid-packaging-machinery"],"_links":{"self":[{"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/posts\/6835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/comments?post=6835"}],"version-history":[{"count":5,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/posts\/6835\/revisions"}],"predecessor-version":[{"id":8867,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/posts\/6835\/revisions\/8867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/media\/6840"}],"wp:attachment":[{"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/media?parent=6835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/categories?post=6835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lintyco.com\/es\/wp-json\/wp\/v2\/tags?post=6835"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}